{"id":8158,"date":"2025-09-10T19:30:21","date_gmt":"2025-09-10T22:30:21","guid":{"rendered":"https:\/\/premierfutsal.com\/br\/?p=8158"},"modified":"2025-09-10T19:30:22","modified_gmt":"2025-09-10T22:30:22","slug":"tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal","status":"publish","type":"post","link":"https:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/","title":{"rendered":"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal!"},"content":{"rendered":"\n<p>Confira agora tudo que se sabe sobre o goleiro do Sindmoto Futsal:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trag\u00e9dia em competi\u00e7\u00e3o no Par\u00e1<\/h2>\n\n\n\n<p>No munic\u00edpio de Augusto Corr\u00eaa (PA), \u00e0 Semana da P\u00e1tria corresponde \u00e0 realiza\u00e7\u00e3o, de como o pr\u00f3prio nome nos diz, uma semana de eventos, celebrada de 1\u00ba a 7 de setembro, sendo um per\u00edodo de intensa programa\u00e7\u00e3o c\u00edvica em todo o Brasil, marcado por atividades que homenageia a Independ\u00eancia Nacional e refor\u00e7am o sentimento de cidadania.<\/p>\n\n\n\n<p>Entre as festividades, est\u00e3o competi\u00e7\u00f5es de futsal com equipes regionais, buscando a premia\u00e7\u00e3o. Contudo, em um dos jogos da competi\u00e7\u00e3o na modalidade masculina terminou em trag\u00e9dia no Par\u00e1.<\/p>\n\n\n\n<p>O goleiro \u00c9dson, conhecido como Pix\u00e9, participava das atividades da Semana da P\u00e1tria de 2025, na cidade de Augusto Corr\u00eaa, quando sofreu um mal s\u00fabito durante a disputa de p\u00eanaltis.<\/p>\n\n\n\n<p>Ap\u00f3s defender uma cobran\u00e7a ao se esticar no canto direito, ele chegou a caminhar em dire\u00e7\u00e3o a um companheiro de equipe, mas caiu em quadra logo em seguida.<\/p>\n\n\n\n<p>Os colegas perceberam imediatamente a gravidade da situa\u00e7\u00e3o e acionaram o socorro m\u00e9dico. \u00c9dson recebeu os primeiros atendimentos ainda no gin\u00e1sio Zezinho de Freitas e, na sequ\u00eancia, foi encaminhado com urg\u00eancia ao hospital municipal. No entanto, n\u00e3o resistiu. At\u00e9 o momento, a causa da morte n\u00e3o foi oficialmente divulgada.<\/p>\n\n\n\n<p>Em raz\u00e3o do falecimento, a prefeitura de Augusto Corr\u00eaa comunicou a suspens\u00e3o das partidas que estavam programadas para a quarta-feira (3). Em sinal de luto e respeito \u00e0 mem\u00f3ria do atleta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nota oficial da federa\u00e7\u00e3o Paranaense de Futsal<\/h3>\n\n\n\n<p>A FEFUSPA (Federa\u00e7\u00e3o Paraense de Futsal) expressou profundo pesar pelo falecimento do goleiro, ressaltando suas qualidades tanto dentro quanto fora das quadras. A entidade tamb\u00e9m manifestou condol\u00eancias sinceras aos familiares, amigos e a toda a comunidade esportiva.<\/p>\n\n\n\n<p><em>\u201cCom imenso pesar recebemos a not\u00edcia do falecimento de Ant\u00f4nio Edson dos Santos Sousa, atleta que marcou sua trajet\u00f3ria com dedica\u00e7\u00e3o, talento e esp\u00edrito de equipe. Sua presen\u00e7a sempre ser\u00e1 lembrada dentro e fora das quadras, n\u00e3o apenas pelo jogador exemplar que foi, mas pela pessoa especial que cativava a todos. Neste momento de dor, expressamos nossos mais sinceros sentimentos aos familiares, amigos e toda a comunidade esportiva. Que encontrem conforto nas boas lembran\u00e7as e na certeza de que Ant\u00f4nio Edson deixa um legado de inspira\u00e7\u00e3o e paix\u00e3o pelo futsal.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira agora tudo que se sabe sobre o goleiro do Sindmoto Futsal: Trag\u00e9dia em competi\u00e7\u00e3o no Par\u00e1 No munic\u00edpio de Augusto Corr\u00eaa (PA), \u00e0 Semana da P\u00e1tria corresponde \u00e0 realiza\u00e7\u00e3o, de como o pr\u00f3prio nome nos diz, uma semana de eventos, celebrada de 1\u00ba a 7 de setembro, sendo um per\u00edodo de intensa programa\u00e7\u00e3o c\u00edvica<\/p>\n","protected":false},"author":2,"featured_media":8159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-8158","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal<\/title>\n<meta name=\"description\" content=\"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal\" \/>\n<meta property=\"og:description\" content=\"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/\" \/>\n<meta property=\"og:site_name\" content=\"PremierFutsal\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T22:30:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T22:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iago Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iago Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/\",\"url\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/\",\"name\":\"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal\",\"isPartOf\":{\"@id\":\"https:\/\/premierfutsal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg\",\"datePublished\":\"2025-09-10T22:30:21+00:00\",\"dateModified\":\"2025-09-10T22:30:22+00:00\",\"author\":{\"@id\":\"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/c75e054665256375a4012f212851bce7\"},\"description\":\"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.\",\"breadcrumb\":{\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage\",\"url\":\"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg\",\"contentUrl\":\"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg\",\"width\":472,\"height\":266,\"caption\":\"jogador-do-sindmoto-futsal-morre-em-quadra-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/premierfutsal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/premierfutsal.com\/br\/#website\",\"url\":\"https:\/\/premierfutsal.com\/br\/\",\"name\":\"PremierFutsal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/premierfutsal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/c75e054665256375a4012f212851bce7\",\"name\":\"Iago Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeab3120944b6ec05e80eb0ddba106cf2c637e3eee24899681b9185f338b781e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeab3120944b6ec05e80eb0ddba106cf2c637e3eee24899681b9185f338b781e?s=96&d=mm&r=g\",\"caption\":\"Iago Henrique\"},\"url\":\"https:\/\/premierfutsal.com\/br\/author\/iago\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal","description":"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/","og_locale":"pt_BR","og_type":"article","og_title":"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal","og_description":"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.","og_url":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/","og_site_name":"PremierFutsal","article_published_time":"2025-09-10T22:30:21+00:00","article_modified_time":"2025-09-10T22:30:22+00:00","og_image":[{"width":472,"height":266,"url":"http:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg","type":"image\/jpeg"}],"author":"Iago Henrique","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Iago Henrique","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/","url":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/","name":"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal! - PremierFutsal","isPartOf":{"@id":"https:\/\/premierfutsal.com\/br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage"},"image":{"@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage"},"thumbnailUrl":"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg","datePublished":"2025-09-10T22:30:21+00:00","dateModified":"2025-09-10T22:30:22+00:00","author":{"@id":"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/c75e054665256375a4012f212851bce7"},"description":"Edson, estava em a\u00e7\u00e3o durante uma partida realizada na cidade de Augusto Corr\u00eaa pelo Sindmoto Futsal, quando fez a defesa e caiu em seguida.","breadcrumb":{"@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#primaryimage","url":"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg","contentUrl":"https:\/\/premierfutsal.com\/br\/wp-content\/uploads\/sites\/2\/2025\/09\/jogador-do-sindmoto-futsal-morre-em-quadra-2025.jpg","width":472,"height":266,"caption":"jogador-do-sindmoto-futsal-morre-em-quadra-2025"},{"@type":"BreadcrumbList","@id":"http:\/\/premierfutsal.com\/br\/tragedia-no-para-goleiro-do-sindmoto-morre-logo-depois-de-defender-penalti-em-jogo-de-futsal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/premierfutsal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Trag\u00e9dia no Par\u00e1: Goleiro do Sindmoto morre logo depois de defender p\u00eanalti em jogo de futsal!"}]},{"@type":"WebSite","@id":"https:\/\/premierfutsal.com\/br\/#website","url":"https:\/\/premierfutsal.com\/br\/","name":"PremierFutsal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/premierfutsal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/c75e054665256375a4012f212851bce7","name":"Iago Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/premierfutsal.com\/br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeab3120944b6ec05e80eb0ddba106cf2c637e3eee24899681b9185f338b781e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeab3120944b6ec05e80eb0ddba106cf2c637e3eee24899681b9185f338b781e?s=96&d=mm&r=g","caption":"Iago Henrique"},"url":"https:\/\/premierfutsal.com\/br\/author\/iago\/"}]}},"_links":{"self":[{"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/posts\/8158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/comments?post=8158"}],"version-history":[{"count":1,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/posts\/8158\/revisions"}],"predecessor-version":[{"id":8160,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/posts\/8158\/revisions\/8160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/media\/8159"}],"wp:attachment":[{"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/media?parent=8158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/categories?post=8158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/premierfutsal.com\/br\/wp-json\/wp\/v2\/tags?post=8158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}